{"id":13985,"date":"2014-06-16T08:15:05","date_gmt":"2014-06-16T06:15:05","guid":{"rendered":"http:\/\/www.sweetie-home.it\/?p=13985"},"modified":"2014-06-16T08:15:05","modified_gmt":"2014-06-16T06:15:05","slug":"amaretti","status":"publish","type":"post","link":"https:\/\/www.sweetie-home.it\/index.php\/2014\/06\/16\/amaretti\/","title":{"rendered":"Amaretti"},"content":{"rendered":"<p><a href=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2014\/06\/Amaretti.jpg\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-13986\" src=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2014\/06\/Amaretti.jpg\" alt=\"Amaretti\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2014\/06\/Amaretti.jpg 600w, https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2014\/06\/Amaretti-200x300.jpg 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Suona come Sweetie che torna a <em>casa<\/em>.<\/p>\n<p>Succede quando ti guardi in giro e trovi quello che ti aspettavi di vedere, proprio dove pensavi che fosse. Gli stessi odori e la stessa luce, che sai come muoverti, anche in mezzo alle ombre.<\/p>\n<p>Quella sicurezza che cerchi quando ti senti un po&#8217; mancare la terra sotto i piedi.<\/p>\n<p>Mi sono presa un pomeriggio a sgranocchiare mandorle e a sporcare la cucina come fosse passato un tornado.<\/p>\n<p>Sono tipo dei biscotti, ma non proprio.<\/p>\n<p>\u00c9 come dire che sono quella che. Ma non proprio.<\/p>\n<p>Di sicuro c&#8217;\u00e8 che sono buoni, parecchio. E se vi piacciono le mandorle &#8211; io vi avviso &#8211; li sgranocchierete come non ci fosse un domani.<\/p>\n<div class=\"easyrecipe\" data-rating=\"#rating#\">\t<link itemprop=\"image\" href=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2014\/06\/Amaretti.jpg\" \/>\n<div class=\"item ERName\">Amaretti<\/div>\n<div class=\"ERClear\"><\/div>\n<div class=\"ERHead\">Author: <span class=\"author\">Sweetie<\/span><\/div>\n<div class=\"ERHead\">Serves: <span class=\"yield\">24 amaretti<\/span><\/div>\n<div class=\"ERSummary summary\">Ricetta tratta da Classici Moderni V.2 di Donna Hay<\/div>\n<div class=\"ERIngredients\">\n<div class=\"ERIngredientsHeader\">Ingredients<\/div>\n<ul class=\"ingredients\">\n<li class=\"ingredient\">200 gr di mandorle<\/li>\n<li class=\"ingredient\">225 gr di zucchero<\/li>\n<li class=\"ingredient\">35 gr di farina<\/li>\n<li class=\"ingredient\">2 albumi<\/li>\n<li class=\"ingredient\">1 cucchiaino di estratto di vaniglia<\/li>\n<\/ul>\n<\/div>\n<div class=\"ERInstructions\">\n<div class=\"ERInstructionsHeader\">Instructions<\/div>\n<div class=\"instructions\">\n<ol>\n<li class=\"instruction\">Tritate grossolanamente le mandorle con lo zucchero.<\/li>\n<li class=\"instruction\">Aggiungete la farina, gli albumi e l&#8217;estratto di vaniglia e lavorateli fino ad amalgamare tutti gli ingredienti.<\/li>\n<li class=\"instruction\">Formate delle palline con due cucchiaini di impasto e disponetele su una teglia coperta da carta forno.<\/li>\n<li class=\"instruction\">Fateli cuocere in forno gi\u00e0 caldo a 180 gradi per 13 minuti o fino a quando non prenderanno colore.<\/li>\n<li class=\"instruction\">Non preoccupatevi se vi sembreranno ancora morbidi, raffreddandosi raggiungeranno la giusta consistenza.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<div class=\"ERNutrition\"><\/div>\n<div class=\"endeasyrecipe\" style=\"display: none;\">3.2.1311<\/div>\n<\/div>\n<a href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.sweetie-home.it%2Findex.php%2F2014%2F06%2F16%2Famaretti%2F&media=https%3A%2F%2Fwww.sweetie-home.it%2Fwp-content%2Fuploads%2F2014%2F06%2FAmaretti.jpg&description=Amaretti\" class=\"pin-it-button\" count-layout=\"horizontal\">Pin It<\/a><!-- relpost-thumb-wrapper --><div class=\"relpost-thumb-wrapper\"><!-- filter-class --><div class=\"relpost-thumb-container\"><h3>Qualche idea in pi\u00f9:<\/h3><div style=\"clear: both\"><\/div><div style=\"clear: both\"><\/div><!-- relpost-block-container --><div class=\"relpost-block-container relpost-block-column-layout\" style=\"--relposth-columns: 3;--relposth-columns_t: 2; --relposth-columns_m: 2\"><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2012\/09\/10\/banana-bread-ed-e-subito-slurp\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Banana bread ed \u00e8 subito slurp!<\/h2><\/div><\/div><\/a><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2012\/06\/13\/fettine-alla-mandorle-by-luca-montersino\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Fettine alla mandorle by Luca Montersino<\/h2><\/div><\/div><\/a><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2011\/12\/20\/un-pensiero-dolcissimo-per-le-feste-sable-al-cacao\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Un pensiero dolcissimo per le feste: sabl\u00e8 al cacao!<\/h2><\/div><\/div><\/a><\/div><!-- close relpost-block-container --><div style=\"clear: both\"><\/div><\/div><!-- close filter class --><\/div><!-- close relpost-thumb-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Suona come Sweetie che torna a casa. Succede quando ti guardi in giro e trovi quello che ti aspettavi di vedere, proprio dove pensavi che fosse. Gli stessi odori e la stessa luce, che sai come muoverti, anche in mezzo alle ombre. Quella sicurezza che cerchi quando ti senti un po&#8217; mancare la terra sotto [&hellip;]<\/p>\n<a href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.sweetie-home.it%2Findex.php%2F2014%2F06%2F16%2Famaretti%2F&media=https%3A%2F%2Fwww.sweetie-home.it%2Fwp-content%2Fuploads%2F2014%2F06%2FAmaretti.jpg&description=Amaretti\" class=\"pin-it-button\" count-layout=\"horizontal\">Pin It<\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[33],"tags":[475,232,51],"_links":{"self":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/13985"}],"collection":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/comments?post=13985"}],"version-history":[{"count":14,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/13985\/revisions"}],"predecessor-version":[{"id":14004,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/13985\/revisions\/14004"}],"wp:attachment":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/media?parent=13985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/categories?post=13985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/tags?post=13985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}