{"id":15362,"date":"2015-04-07T10:01:59","date_gmt":"2015-04-07T08:01:59","guid":{"rendered":"http:\/\/www.sweetie-home.it\/?p=15362"},"modified":"2015-04-07T10:01:59","modified_gmt":"2015-04-07T08:01:59","slug":"hot-cross-buns","status":"publish","type":"post","link":"https:\/\/www.sweetie-home.it\/index.php\/2015\/04\/07\/hot-cross-buns\/","title":{"rendered":"Hot Cross Buns"},"content":{"rendered":"<p><a href=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2015\/04\/HotBunsCross-003-6-ok-copy.jpg\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-15365\" src=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2015\/04\/HotBunsCross-003-6-ok-copy.jpg\" alt=\"Hot Cross Buns\" width=\"600\" height=\"900\" srcset=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2015\/04\/HotBunsCross-003-6-ok-copy.jpg 600w, https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2015\/04\/HotBunsCross-003-6-ok-copy-200x300.jpg 200w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Chiss\u00e0 se mi ricordo\u00a0come si fa.<\/p>\n<p>Sporcarmi le mani con la farina, fare\u00a0finta di avere pazienza per vedere l&#8217;effetto che fa e poi impiastricciare la reflex.<\/p>\n<p>Stendere un telo di lino per terra, litigare con il bianco che non \u00e8 abbastanza bianco e fermare due scatti per raccontare un impasto che \u00e8 cominciato la mattina di pasqua e che \u00e8 uscito dal forno giusto in tempo per fare merenda.<\/p>\n<p>Chiss\u00e0 se ho\u00a0ancora voglia\u00a0di\u00a0scrivere sogni,\u00a0raccontare pensieri ad alta voce e fermare su carta quei km macinati tra i\u00a0canali di Amsterdam e le strade dipinte\u00a0di una\u00a0Roma che\u00a0non ti aspetti, ancora chiusi in una bustina di tela, tra biglietti del tram e fogli strappati.<\/p>\n<p>Forse c&#8217;\u00e8 un tempo fatto per\u00a0raccontare e un tempo in cui semplicemente si fa.<\/p>\n<p>Doveva essere una torta al cioccolato. Avevo in mente di\u00a0tornare da queste parti con un plumcake incredibilmente denso e gustoso. E invece eccomi qui, con questi panini\u00a0profumatissimi, nonostante la croce non pervenuta e questa foto rubata alla voglia di essere altrove<\/p>\n<p>Richiedono un po&#8217; di tempo, ma vi assicuro che \u00e8 tempo speso bene, profumato di agrumi, cannella, zenzero e chiodi di garofano.<\/p>\n<p>Voi potreste mettervi ad impastare, mentre io cerco di capire cosa voglio fare\u00a0con questo spazio\u00a0e con\u00a0i kili di burro e cioccolato\u00a0raccontati fin qui.<\/p>\n<p>Se torno non lo so, voi per\u00f2 non perdete il vizio di sgranocchiare biscotti.<\/p>\n<div class=\"easyrecipe\" data-rating=\"0\">\t<link itemprop=\"image\" href=\"https:\/\/www.sweetie-home.it\/wp-content\/uploads\/2015\/04\/HotBunsCross-003-6-ok-copy.jpg\" \/>\n<div class=\"item ERName\">Hot Cross Buns<\/div>\n<div class=\"ERClear\"><\/div>\n<div class=\"ERHead\">Author: <span class=\"author\">Sweetie<\/span><\/div>\n<div class=\"ERSummary summary\">Ricetta tratta da &#8220;Come si fa il pane&#8221; di Emmanuel Hadjiandreou<\/div>\n<div class=\"ERIngredients\">\n<div class=\"ERIngredientsHeader\">Ingredients<\/div>\n<ul class=\"ingredients\">\n<li class=\"ingredient\">PER LE CROCI<\/li>\n<li class=\"ingredient\">90 ml di acqua<\/li>\n<li class=\"ingredient\">40 ml di olio vegetale<\/li>\n<li class=\"ingredient\">75 gr di farina<\/li>\n<li class=\"ingredient\">2 gr di sale<\/li>\n<li class=\"ingredient\">PER LA GLASSA<\/li>\n<li class=\"ingredient\">250 ml di acqua<\/li>\n<li class=\"ingredient\">150 gr di zucchero<\/li>\n<li class=\"ingredient\">1\/2 arancia non trattata, tagliata in 4<\/li>\n<li class=\"ingredient\">1\/2 limone non trattato, tagliato in 4<\/li>\n<li class=\"ingredient\">2 bastoncini di cannella<\/li>\n<li class=\"ingredient\">5 chiodi di garofano<\/li>\n<li class=\"ingredient\">3 semi di anice stellato<\/li>\n<li class=\"ingredient\">PER IL PREIMPASTO<\/li>\n<li class=\"ingredient\">10 gr di lievito fresco (o 5 gr di lievito secco attivo)<\/li>\n<li class=\"ingredient\">40 gr di zucchero<\/li>\n<li class=\"ingredient\">200 ml di acqua calda<\/li>\n<li class=\"ingredient\">200 gr di farina<\/li>\n<li class=\"ingredient\">PER L&#8217;IMPASTO<\/li>\n<li class=\"ingredient\">250 gr di uvetta (in originale 150 gr di uvetta + 150 gr di uvetta di Corinto)<\/li>\n<li class=\"ingredient\">1 cucchiaino di zenzero in polvere<\/li>\n<li class=\"ingredient\">1 cucchiaino di cannella in polvere<\/li>\n<li class=\"ingredient\">1\/4 di cucchiaioni chiodi di garofano<\/li>\n<li class=\"ingredient\">la scorza grattugiata di 2 arance non trattate<\/li>\n<li class=\"ingredient\">la scorza grattugiata di 3 limoni non trattati<\/li>\n<li class=\"ingredient\">200 gr di farina per pane<\/li>\n<li class=\"ingredient\">2 gr di sale<\/li>\n<li class=\"ingredient\">90 gr di burro ammorbidito<\/li>\n<li class=\"ingredient\">1 uovo grande<\/li>\n<\/ul>\n<\/div>\n<div class=\"ERInstructions\">\n<div class=\"ERInstructionsHeader\">Instructions<\/div>\n<div class=\"instructions\">\n<ol>\n<li class=\"instruction\">PER LE CROCI<\/li>\n<li class=\"instruction\">Mescolate l&#8217;acqua e l&#8217;olio. In un secondo contenitore mescolate la farina e il sale.<\/li>\n<li class=\"instruction\">Unite il composto con l&#8217;olio a quello con la farina e il sale e mescolate con un cucchiaio di legno fino a ottenere una pasta morbida e liscia. Coprite e tenete al fresco fino al momento di utilizzarla (N.B. io ho ottenuto un impasto troppo liquido che non ha tenuto bene la forma. Prossima volta aggiungo un cucchiaio in pi\u00f9 di farina e tengo in frigorifero da subito)<\/li>\n<li class=\"instruction\">PER LA GLASSA<\/li>\n<li class=\"instruction\">Mettete l&#8217;acqua, lo zucchero, la 1\/2 arancia e il 1\/2 limone tagliati in quattro parti, i bastoncini di cannella, i chiodi di garofano e l&#8217;anice stellato in una casseruola. Portate ad ebollizione.<\/li>\n<li class=\"instruction\">Quando inizia a bollire, togliete dal fuoco e mettete da parte, in un posto fresco, in modo che le spezie e gli agrumi rilascino gli aromi.<\/li>\n<li class=\"instruction\">Potete preparare questa glassa anche il giorno prima e conservarla in frigorifero fino al momento di utilizzarla.<\/li>\n<li class=\"instruction\">PER IL PREIMPASTO<\/li>\n<li class=\"instruction\">In una ciotola pesate il lievito, unite lo zucchero e l&#8217;acqua calda e mescolate finch\u00e9 si sono sciolti<\/li>\n<li class=\"instruction\">Unite la prima parte della farina e mescolate con un cucchiaio di legno per amalgamare bene. Questo \u00e8 il prefermento.<\/li>\n<li class=\"instruction\">Coprite e fate fermentare in un posto caldo (per me forno con luce accesa) finch\u00e9 raddoppia di volume. All&#8217;incirca 30\/ 40 minuti<\/li>\n<li class=\"instruction\">PER L&#8217;IMPASTO<\/li>\n<li class=\"instruction\">In una ciotola pesate l&#8217;uvetta e poi aggiungete le spezie e le scorze. Mescolate bene il tutto e tenete da parte.<\/li>\n<li class=\"instruction\">In un&#8217;altra ciotola, mescolate i 200 gr di farina per pane (vedi. ingredienti per impasto) insieme al sale.<\/li>\n<li class=\"instruction\">Unite il burro a pezzetti e lavorate il tutto con la punta delle dita fino a quando non rimarranno pi\u00f9 pezzi grossi di burro.<\/li>\n<li class=\"instruction\">Quando il prefermento sar\u00e0 lievitato (30\/40 minuti circa), unitelo all&#8217;impasto di farina e burro, insieme all&#8217;uovo precedentemente sbattuto. Amalgamate il tutto con le mani o con un cucchiaio di legno.<\/li>\n<li class=\"instruction\">Coprite e fate riposare per 10 minuti.<\/li>\n<li class=\"instruction\">Dopo 10 minuti riprendete l&#8217;impasto e lavoratelo nella ciotola in questo modo: tirate dal bordo un pezzo di impasto e premetelo al centro. Girate leggermente la ciotola e ripetete con un&#8217;altra porzione di impasto, sempre premendola al centro. Ripetete per altre 8 volte, girando a mano a mano la ciotola. Procedendo in questo modo vi accorgerete che l&#8217;impasto inizier\u00e0 a fare resistenza.<\/li>\n<li class=\"instruction\">Coprire e fate riposare altri 10 minuti. Ripetete l&#8217;operazione appena descritta per altre 3 volte, facendo riposare l&#8217;impasto per 10 minuti tra un&#8217;operazione e l&#8217;altra.<\/li>\n<li class=\"instruction\">Aggiungete all&#8217;impasto il composto con l&#8217;uvetta e impastate delicatamente il tutto, fino ad amalgamare gli ingredienti.<\/li>\n<li class=\"instruction\">Coprite e fate lievitare per altri 30 minuti.<\/li>\n<li class=\"instruction\">A questo punto potete proseguire oppure mettere l&#8217;impasto in frigorifero fino al giorno dopo. In questo secondo caso, dopo aver ripreso l&#8217;impasto dal frigorifero, fatelo riposare a temperatura ambiente per 15\/20 minuti prima di continuare la lavorazione.<\/li>\n<li class=\"instruction\">Spolverate di farina un piano di lavoro e trasferiteci l&#8217;impasto.<\/li>\n<li class=\"instruction\">Dopo 30 minuti, dividete l&#8217;impasto in 14\/15 pezzi uguali, aiutandovi con un raschiapasta o con un coltello affilato. Ogni pezzo deve pesare circa 70 gr per essere precisi usate una bilancia.<\/li>\n<li class=\"instruction\">Prendete un pezzo di impasto tra le mani e rotolatelo fino ad ottenere una pallina sferica. Mettetela sulla teglia e ripetete con l&#8217;impasto restante. Lasciate un po&#8217; di spazio tra una e l&#8217;altra in modo che abbiano tempo di lievitare.<\/li>\n<li class=\"instruction\">Coprite e fate lievitare fino al raddoppio.<\/li>\n<li class=\"instruction\">Circa 20 minuti prima di infornare, accendete il forno a 220 gradi, posizionando una teglia sul fondo.<\/li>\n<li class=\"instruction\">Intanto riempite una sac a poche con il composto per le croci e formate delle righe continue sulla superficie dei panini in entrambe le direzioni.<\/li>\n<li class=\"instruction\">Infornate la teglia con i panini, versate una tazza d&#8217;acqua nella teglia che avete posizionato sul fondo del forno e abbassate la temperatura a 180 gradi.<\/li>\n<li class=\"instruction\">Cuocete per 10-15 minuti o finch\u00e9 non saranno dorati.<\/li>\n<li class=\"instruction\">Sfornateli e spennellateli con la glassa fredda, tenuta da parte.<\/li>\n<li class=\"instruction\">Fate raffreddare sulla teglia prima di servirli.<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<div class=\"ERNutrition\"><\/div>\n<div class=\"endeasyrecipe\" style=\"display: none;\">3.2.2929<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<a href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.sweetie-home.it%2Findex.php%2F2015%2F04%2F07%2Fhot-cross-buns%2F&media=https%3A%2F%2Fwww.sweetie-home.it%2Fwp-content%2Fuploads%2F2015%2F04%2FHotBunsCross-003-6-ok-copy.jpg&description=\" class=\"pin-it-button\" count-layout=\"horizontal\">Pin It<\/a><!-- relpost-thumb-wrapper --><div class=\"relpost-thumb-wrapper\"><!-- filter-class --><div class=\"relpost-thumb-container\"><h3>Qualche idea in pi\u00f9:<\/h3><div style=\"clear: both\"><\/div><div style=\"clear: both\"><\/div><!-- relpost-block-container --><div class=\"relpost-block-container relpost-block-column-layout\" style=\"--relposth-columns: 3;--relposth-columns_t: 2; --relposth-columns_m: 2\"><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2011\/06\/20\/muffin-morbidissimi-alle-mele\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Muffin morbidissimi alle mele<\/h2><\/div><\/div><\/a><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2013\/05\/01\/chocolate-and-banana-bread\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Chocolate and banana bread<\/h2><\/div><\/div><\/a><a href=\"https:\/\/www.sweetie-home.it\/index.php\/2012\/12\/19\/gingerbread\/\"class=\"relpost-block-single\" ><div class=\"relpost-custom-block-single\"><div class=\"relpost-block-single-image\" aria-hidden=\"true\" role=\"img\" style=\"background: transparent url(https:\/\/www.sweetie-home.it\/wp-content\/plugins\/related-posts-thumbnails\/img\/default.png) no-repeat scroll 0% 0%; width: 150px; height: 150px;aspect-ratio:1\/1\"><\/div><div class=\"relpost-block-single-text\"  style=\"height: 75px;font-family: Arial;  font-size: 12px;  color: #333333;\"><h2 class=\"relpost_card_title\">Gingerbread<\/h2><\/div><\/div><\/a><\/div><!-- close relpost-block-container --><div style=\"clear: both\"><\/div><\/div><!-- close filter class --><\/div><!-- close relpost-thumb-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Chiss\u00e0 se mi ricordo\u00a0come si fa. Sporcarmi le mani con la farina, fare\u00a0finta di avere pazienza per vedere l&#8217;effetto che fa e poi impiastricciare la reflex. Stendere un telo di lino per terra, litigare con il bianco che non \u00e8 abbastanza bianco e fermare due scatti per raccontare un impasto che \u00e8 cominciato la mattina [&hellip;]<\/p>\n<a href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https%3A%2F%2Fwww.sweetie-home.it%2Findex.php%2F2015%2F04%2F07%2Fhot-cross-buns%2F&media=https%3A%2F%2Fwww.sweetie-home.it%2Fwp-content%2Fuploads%2F2015%2F04%2FHotBunsCross-003-6-ok-copy.jpg&description=\" class=\"pin-it-button\" count-layout=\"horizontal\">Pin It<\/a>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[84],"tags":[104,42,473,54,472,114],"_links":{"self":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/15362"}],"collection":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/comments?post=15362"}],"version-history":[{"count":18,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/15362\/revisions"}],"predecessor-version":[{"id":15382,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/posts\/15362\/revisions\/15382"}],"wp:attachment":[{"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/media?parent=15362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/categories?post=15362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sweetie-home.it\/index.php\/wp-json\/wp\/v2\/tags?post=15362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}